{"id":16835,"date":"2026-05-13T06:38:41","date_gmt":"2026-05-13T06:38:41","guid":{"rendered":"https:\/\/www.iese.edu\/es\/insight\/?post_type=article&#038;p=16835"},"modified":"2026-05-13T06:38:41","modified_gmt":"2026-05-13T06:38:41","slug":"integrarse-o-destacar-el-papel-del-directivo-ante-las-nuevas-incorporaciones","status":"publish","type":"article","link":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/","title":{"rendered":"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones"},"author":83,"featured_media":16841,"menu_order":0,"template":"","tags":[72,79],"class_list":["post-16835","article","type-article","status-publish","has-post-thumbnail","hentry","tag-estrategia","tag-liderazgo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones | IESE Insight<\/title>\n<meta name=\"description\" content=\"Descubre un enfoque centrado en las habilidades y la personalidad de los nuevos empleados para sacar lo mejor de ellos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones\" \/>\n<meta property=\"og:description\" content=\"Descubre un enfoque centrado en las habilidades y la personalidad de los nuevos empleados para sacar lo mejor de ellos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/\" \/>\n<meta property=\"og:site_name\" content=\"IESE Insight\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2026\/05\/apreton-manos-oficina.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/\"},\"author\":{\"name\":\"apadierna\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#\\\/schema\\\/person\\\/961d76353ab73d0158b9d12271cb7f50\"},\"headline\":\"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones\",\"datePublished\":\"2026-05-13T06:38:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/\"},\"wordCount\":11,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/apreton-manos-oficina.webp\",\"keywords\":[\"estrategia\",\"liderazgo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/\",\"name\":\"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones | IESE Insight\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/apreton-manos-oficina.webp\",\"datePublished\":\"2026-05-13T06:38:41+00:00\",\"description\":\"Descubre un enfoque centrado en las habilidades y la personalidad de los nuevos empleados para sacar lo mejor de ellos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/apreton-manos-oficina.webp\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/apreton-manos-oficina.webp\",\"width\":1024,\"height\":700,\"caption\":\"Dos mujeres d\u00e1ndose un apret\u00f3n de manos en una sala de oficina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/articulos\\\/incorporaciones-integrarse-destacar-supervisor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/\",\"name\":\"IESE Insight\",\"description\":\"Relevant Business Knowledge\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#organization\",\"name\":\"IESE Insight\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/11\\\/Logo-IESE.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/11\\\/Logo-IESE.png\",\"width\":290,\"height\":290,\"caption\":\"IESE Insight\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/insight\\\/#\\\/schema\\\/person\\\/961d76353ab73d0158b9d12271cb7f50\",\"name\":\"apadierna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f503a292b0be90b58d0d123cb475cb72df3705eced06d098bd8e842d1084f5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f503a292b0be90b58d0d123cb475cb72df3705eced06d098bd8e842d1084f5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f503a292b0be90b58d0d123cb475cb72df3705eced06d098bd8e842d1084f5f?s=96&d=mm&r=g\",\"caption\":\"apadierna\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones | IESE Insight","description":"Descubre un enfoque centrado en las habilidades y la personalidad de los nuevos empleados para sacar lo mejor de ellos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones","og_description":"Descubre un enfoque centrado en las habilidades y la personalidad de los nuevos empleados para sacar lo mejor de ellos.","og_url":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/","og_site_name":"IESE Insight","og_image":[{"width":1024,"height":700,"url":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2026\/05\/apreton-manos-oficina.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#article","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/"},"author":{"name":"apadierna","@id":"https:\/\/www.iese.edu\/es\/insight\/#\/schema\/person\/961d76353ab73d0158b9d12271cb7f50"},"headline":"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones","datePublished":"2026-05-13T06:38:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/"},"wordCount":11,"publisher":{"@id":"https:\/\/www.iese.edu\/es\/insight\/#organization"},"image":{"@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2026\/05\/apreton-manos-oficina.webp","keywords":["estrategia","liderazgo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/","url":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/","name":"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones | IESE Insight","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/insight\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2026\/05\/apreton-manos-oficina.webp","datePublished":"2026-05-13T06:38:41+00:00","description":"Descubre un enfoque centrado en las habilidades y la personalidad de los nuevos empleados para sacar lo mejor de ellos.","breadcrumb":{"@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#primaryimage","url":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2026\/05\/apreton-manos-oficina.webp","contentUrl":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2026\/05\/apreton-manos-oficina.webp","width":1024,"height":700,"caption":"Dos mujeres d\u00e1ndose un apret\u00f3n de manos en una sala de oficina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.edu\/es\/insight\/articulos\/incorporaciones-integrarse-destacar-supervisor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.iese.edu\/es\/insight\/"},{"@type":"ListItem","position":2,"name":"\u00bfIntegrarse o destacar? El papel del directivo ante las nuevas incorporaciones"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.edu\/es\/insight\/#website","url":"https:\/\/www.iese.edu\/es\/insight\/","name":"IESE Insight","description":"Relevant Business Knowledge","publisher":{"@id":"https:\/\/www.iese.edu\/es\/insight\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.edu\/es\/insight\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iese.edu\/es\/insight\/#organization","name":"IESE Insight","url":"https:\/\/www.iese.edu\/es\/insight\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/insight\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2022\/11\/Logo-IESE.png","contentUrl":"https:\/\/www.iese.edu\/es\/insight\/wp-content\/uploads\/sites\/4\/2022\/11\/Logo-IESE.png","width":290,"height":290,"caption":"IESE Insight"},"image":{"@id":"https:\/\/www.iese.edu\/es\/insight\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.iese.edu\/es\/insight\/#\/schema\/person\/961d76353ab73d0158b9d12271cb7f50","name":"apadierna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4f503a292b0be90b58d0d123cb475cb72df3705eced06d098bd8e842d1084f5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f503a292b0be90b58d0d123cb475cb72df3705eced06d098bd8e842d1084f5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f503a292b0be90b58d0d123cb475cb72df3705eced06d098bd8e842d1084f5f?s=96&d=mm&r=g","caption":"apadierna"}}]}},"_links":{"self":[{"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/article\/16835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/types\/article"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/users\/83"}],"version-history":[{"count":6,"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/article\/16835\/revisions"}],"predecessor-version":[{"id":16849,"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/article\/16835\/revisions\/16849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/media\/16841"}],"wp:attachment":[{"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/media?parent=16835"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.edu\/es\/insight\/wp-json\/wp\/v2\/tags?post=16835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}