{"id":20583,"date":"2026-03-25T10:15:26","date_gmt":"2026-03-25T10:15:26","guid":{"rendered":"https:\/\/www.iese.edu\/es\/?p=20583"},"modified":"2026-03-25T11:11:06","modified_gmt":"2026-03-25T11:11:06","slug":"iese-9-millones-euros-becas-talento-global","status":"publish","type":"post","link":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/","title":{"rendered":"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":20584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[240,3214,25,372,449],"class_list":["post-20583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-emba","tag-master-in-management","tag-mba","tag-phd","tag-programa-de-becas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global - IESE<\/title>\n<meta name=\"description\" content=\"La dotaci\u00f3n crece un 35% y permite apoyar a 787 alumnos, en un contexto de creciente dificultad para acceder a la educaci\u00f3n superior.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global\" \/>\n<meta property=\"og:description\" content=\"La dotaci\u00f3n crece un 35% y permite apoyar a 787 alumnos, en un contexto de creciente dificultad para acceder a la educaci\u00f3n superior.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/\" \/>\n<meta property=\"og:site_name\" content=\"IESE\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T10:15:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T11:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"yrivero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"yrivero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/\"},\"author\":{\"name\":\"yrivero\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/person\\\/e2e25bc9226605bba505c3a1f8542863\"},\"headline\":\"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global\",\"datePublished\":\"2026-03-25T10:15:26+00:00\",\"dateModified\":\"2026-03-25T11:11:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/\"},\"wordCount\":15,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/2.png\",\"keywords\":[\"EMBA\",\"Master in Management\",\"MBA\",\"PhD\",\"programa de becas\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/\",\"name\":\"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global - IESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/2.png\",\"datePublished\":\"2026-03-25T10:15:26+00:00\",\"dateModified\":\"2026-03-25T11:11:06+00:00\",\"description\":\"La dotaci\u00f3n crece un 35% y permite apoyar a 787 alumnos, en un contexto de creciente dificultad para acceder a la educaci\u00f3n superior.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/2.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/2.png\",\"width\":1024,\"height\":570},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/iese-9-millones-euros-becas-talento-global\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\",\"name\":\"IESE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\",\"name\":\"IESE Business School\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Logo-IESE.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Logo-IESE.png\",\"width\":290,\"height\":290,\"caption\":\"IESE Business School\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/person\\\/e2e25bc9226605bba505c3a1f8542863\",\"name\":\"yrivero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8e593638a92993070cb0d642bb1a903234eb90d72457af29da7ffd664051da9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8e593638a92993070cb0d642bb1a903234eb90d72457af29da7ffd664051da9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8e593638a92993070cb0d642bb1a903234eb90d72457af29da7ffd664051da9?s=96&d=mm&r=g\",\"caption\":\"yrivero\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global - IESE","description":"La dotaci\u00f3n crece un 35% y permite apoyar a 787 alumnos, en un contexto de creciente dificultad para acceder a la educaci\u00f3n superior.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/","og_locale":"es_ES","og_type":"article","og_title":"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global","og_description":"La dotaci\u00f3n crece un 35% y permite apoyar a 787 alumnos, en un contexto de creciente dificultad para acceder a la educaci\u00f3n superior.","og_url":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/","og_site_name":"IESE","article_published_time":"2026-03-25T10:15:26+00:00","article_modified_time":"2026-03-25T11:11:06+00:00","og_image":[{"width":1024,"height":570,"url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/2.png","type":"image\/png"}],"author":"yrivero","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"yrivero","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#article","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/"},"author":{"name":"yrivero","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/person\/e2e25bc9226605bba505c3a1f8542863"},"headline":"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global","datePublished":"2026-03-25T10:15:26+00:00","dateModified":"2026-03-25T11:11:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/"},"wordCount":15,"publisher":{"@id":"https:\/\/www.iese.edu\/es\/#organization"},"image":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/2.png","keywords":["EMBA","Master in Management","MBA","PhD","programa de becas"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/","url":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/","name":"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global - IESE","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/2.png","datePublished":"2026-03-25T10:15:26+00:00","dateModified":"2026-03-25T11:11:06+00:00","description":"La dotaci\u00f3n crece un 35% y permite apoyar a 787 alumnos, en un contexto de creciente dificultad para acceder a la educaci\u00f3n superior.","breadcrumb":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#primaryimage","url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/2.png","contentUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2026\/03\/2.png","width":1024,"height":570},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.edu\/es\/noticias\/iese-9-millones-euros-becas-talento-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iese.edu\/es\/"},{"@type":"ListItem","position":2,"name":"El IESE destina m\u00e1s de 9 millones de euros a becas para atraer talento global"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.edu\/es\/#website","url":"https:\/\/www.iese.edu\/es\/","name":"IESE","description":"","publisher":{"@id":"https:\/\/www.iese.edu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.edu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iese.edu\/es\/#organization","name":"IESE Business School","url":"https:\/\/www.iese.edu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/12\/Logo-IESE.png","contentUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/12\/Logo-IESE.png","width":290,"height":290,"caption":"IESE Business School"},"image":{"@id":"https:\/\/www.iese.edu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/person\/e2e25bc9226605bba505c3a1f8542863","name":"yrivero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a8e593638a92993070cb0d642bb1a903234eb90d72457af29da7ffd664051da9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8e593638a92993070cb0d642bb1a903234eb90d72457af29da7ffd664051da9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8e593638a92993070cb0d642bb1a903234eb90d72457af29da7ffd664051da9?s=96&d=mm&r=g","caption":"yrivero"}}]}},"_links":{"self":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts\/20583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/comments?post=20583"}],"version-history":[{"count":2,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts\/20583\/revisions"}],"predecessor-version":[{"id":20586,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts\/20583\/revisions\/20586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/media\/20584"}],"wp:attachment":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/media?parent=20583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/categories?post=20583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/tags?post=20583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}