{"id":5186,"date":"2020-02-27T12:30:24","date_gmt":"2020-02-27T12:30:24","guid":{"rendered":"https:\/\/www.iese.edu\/es\/?p=5186"},"modified":"2023-06-09T10:33:32","modified_gmt":"2023-06-09T10:33:32","slug":"ecosistema-emprendedor-grandes-empresas-startups","status":"publish","type":"post","link":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/","title":{"rendered":"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups'"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":5187,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[4638,5493,70],"class_list":["post-5186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-digitalizacion","tag-emprendimiento","tag-innovacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hacia un ecosistema emprendedor formado por grandes empresas y &#039;startups&#039; - IESE<\/title>\n<meta name=\"description\" content=\"El IESE ha participado esta semana en el Tech Spirit Barcelona, unas jornadas sobre emprendimiento e innovaci\u00f3n organizadas por el ecosistema digital de la ciudad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hacia un ecosistema emprendedor formado por grandes empresas y &#039;startups&#039;\" \/>\n<meta property=\"og:description\" content=\"El IESE ha participado esta semana en el Tech Spirit Barcelona, unas jornadas sobre emprendimiento e innovaci\u00f3n organizadas por el ecosistema digital de la ciudad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/\" \/>\n<meta property=\"og:site_name\" content=\"IESE\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-27T12:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T10:33:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/02\/BarcelonaTechSpirit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mwallin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mwallin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/\"},\"author\":{\"name\":\"mwallin\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/person\\\/a527806e9ff52bc3dd00369a72f77add\"},\"headline\":\"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups'\",\"datePublished\":\"2020-02-27T12:30:24+00:00\",\"dateModified\":\"2023-06-09T10:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/BarcelonaTechSpirit.jpg\",\"keywords\":[\"digitalizaci\u00f3n\",\"Emprendimiento\",\"innovaci\u00f3n\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/\",\"name\":\"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups' - IESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/BarcelonaTechSpirit.jpg\",\"datePublished\":\"2020-02-27T12:30:24+00:00\",\"dateModified\":\"2023-06-09T10:33:32+00:00\",\"description\":\"El IESE ha participado esta semana en el Tech Spirit Barcelona, unas jornadas sobre emprendimiento e innovaci\u00f3n organizadas por el ecosistema digital de la ciudad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/BarcelonaTechSpirit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/BarcelonaTechSpirit.jpg\",\"width\":1024,\"height\":570,\"caption\":\"BarcelonaTechSpirit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/noticias\\\/ecosistema-emprendedor-grandes-empresas-startups\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hacia un ecosistema emprendedor formado por grandes empresas y &#8216;startups&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\",\"name\":\"IESE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\",\"name\":\"IESE Business School\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Logo-IESE.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Logo-IESE.png\",\"width\":290,\"height\":290,\"caption\":\"IESE Business School\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/person\\\/a527806e9ff52bc3dd00369a72f77add\",\"name\":\"mwallin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b7c0295aa2daf5f8132b1d448ce2135da01f1563fc449a15668967559983f42?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b7c0295aa2daf5f8132b1d448ce2135da01f1563fc449a15668967559983f42?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b7c0295aa2daf5f8132b1d448ce2135da01f1563fc449a15668967559983f42?s=96&d=mm&r=g\",\"caption\":\"mwallin\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups' - IESE","description":"El IESE ha participado esta semana en el Tech Spirit Barcelona, unas jornadas sobre emprendimiento e innovaci\u00f3n organizadas por el ecosistema digital de la ciudad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/","og_locale":"es_ES","og_type":"article","og_title":"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups'","og_description":"El IESE ha participado esta semana en el Tech Spirit Barcelona, unas jornadas sobre emprendimiento e innovaci\u00f3n organizadas por el ecosistema digital de la ciudad.","og_url":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/","og_site_name":"IESE","article_published_time":"2020-02-27T12:30:24+00:00","article_modified_time":"2023-06-09T10:33:32+00:00","og_image":[{"width":1024,"height":570,"url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/02\/BarcelonaTechSpirit.jpg","type":"image\/jpeg"}],"author":"mwallin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mwallin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#article","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/"},"author":{"name":"mwallin","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/person\/a527806e9ff52bc3dd00369a72f77add"},"headline":"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups'","datePublished":"2020-02-27T12:30:24+00:00","dateModified":"2023-06-09T10:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/"},"wordCount":10,"publisher":{"@id":"https:\/\/www.iese.edu\/es\/#organization"},"image":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/02\/BarcelonaTechSpirit.jpg","keywords":["digitalizaci\u00f3n","Emprendimiento","innovaci\u00f3n"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/","url":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/","name":"Hacia un ecosistema emprendedor formado por grandes empresas y 'startups' - IESE","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/02\/BarcelonaTechSpirit.jpg","datePublished":"2020-02-27T12:30:24+00:00","dateModified":"2023-06-09T10:33:32+00:00","description":"El IESE ha participado esta semana en el Tech Spirit Barcelona, unas jornadas sobre emprendimiento e innovaci\u00f3n organizadas por el ecosistema digital de la ciudad.","breadcrumb":{"@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#primaryimage","url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/02\/BarcelonaTechSpirit.jpg","contentUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/02\/BarcelonaTechSpirit.jpg","width":1024,"height":570,"caption":"BarcelonaTechSpirit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.edu\/es\/noticias\/ecosistema-emprendedor-grandes-empresas-startups\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iese.edu\/es\/"},{"@type":"ListItem","position":2,"name":"Hacia un ecosistema emprendedor formado por grandes empresas y &#8216;startups&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.edu\/es\/#website","url":"https:\/\/www.iese.edu\/es\/","name":"IESE","description":"","publisher":{"@id":"https:\/\/www.iese.edu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.edu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iese.edu\/es\/#organization","name":"IESE Business School","url":"https:\/\/www.iese.edu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/12\/Logo-IESE.png","contentUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/12\/Logo-IESE.png","width":290,"height":290,"caption":"IESE Business School"},"image":{"@id":"https:\/\/www.iese.edu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/person\/a527806e9ff52bc3dd00369a72f77add","name":"mwallin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b7c0295aa2daf5f8132b1d448ce2135da01f1563fc449a15668967559983f42?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b7c0295aa2daf5f8132b1d448ce2135da01f1563fc449a15668967559983f42?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b7c0295aa2daf5f8132b1d448ce2135da01f1563fc449a15668967559983f42?s=96&d=mm&r=g","caption":"mwallin"}}]}},"_links":{"self":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts\/5186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/comments?post=5186"}],"version-history":[{"count":15,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts\/5186\/revisions"}],"predecessor-version":[{"id":14571,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/posts\/5186\/revisions\/14571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/media\/5187"}],"wp:attachment":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/media?parent=5186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/categories?post=5186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/tags?post=5186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}