{"id":1284,"date":"2018-11-06T18:45:18","date_gmt":"2018-11-06T18:45:18","guid":{"rendered":"http:\/\/www.iese.edu\/es\/professor\/albert-valenti\/"},"modified":"2025-10-13T10:41:55","modified_gmt":"2025-10-13T10:41:55","slug":"albert-valenti","status":"publish","type":"professor","link":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/","title":{"rendered":"Albert Valent\u00ed"},"author":1,"featured_media":19733,"menu_order":0,"template":"","class_list":["post-1284","professor","type-professor","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Albert Valent\u00ed | IESE Business School<\/title>\n<meta name=\"description\" content=\"Albert Valent\u00ed es profesor agregado del departamento de Direcci\u00f3n Comercial de IESE Business School.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Albert Valent\u00ed\" \/>\n<meta property=\"og:description\" content=\"Albert Valent\u00ed es profesor agregado del departamento de Direcci\u00f3n Comercial de IESE Business School.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/\" \/>\n<meta property=\"og:site_name\" content=\"IESE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T10:41:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2018\/11\/Albert-Valenti-2025-b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"205\" \/>\n\t<meta property=\"og:image:height\" content=\"205\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/\",\"name\":\"Albert Valent\u00ed | IESE Business School\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Albert-Valenti-2025-b.jpg\",\"datePublished\":\"2018-11-06T18:45:18+00:00\",\"dateModified\":\"2025-10-13T10:41:55+00:00\",\"description\":\"Albert Valent\u00ed es profesor agregado del departamento de Direcci\u00f3n Comercial de IESE Business School.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Albert-Valenti-2025-b.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/Albert-Valenti-2025-b.jpg\",\"width\":205,\"height\":205,\"caption\":\"Albert Valent\u00ed | IESE Business School\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/claustro-investigacion\\\/claustro\\\/albert-valenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Albert Valent\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\",\"name\":\"IESE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#organization\",\"name\":\"IESE Business School\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Logo-IESE.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/Logo-IESE.png\",\"width\":290,\"height\":290,\"caption\":\"IESE Business School\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.edu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Albert Valent\u00ed | IESE Business School","description":"Albert Valent\u00ed es profesor agregado del departamento de Direcci\u00f3n Comercial de IESE Business School.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/","og_locale":"es_ES","og_type":"article","og_title":"Albert Valent\u00ed","og_description":"Albert Valent\u00ed es profesor agregado del departamento de Direcci\u00f3n Comercial de IESE Business School.","og_url":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/","og_site_name":"IESE","article_modified_time":"2025-10-13T10:41:55+00:00","og_image":[{"width":205,"height":205,"url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2018\/11\/Albert-Valenti-2025-b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/","url":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/","name":"Albert Valent\u00ed | IESE Business School","isPartOf":{"@id":"https:\/\/www.iese.edu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2018\/11\/Albert-Valenti-2025-b.jpg","datePublished":"2018-11-06T18:45:18+00:00","dateModified":"2025-10-13T10:41:55+00:00","description":"Albert Valent\u00ed es profesor agregado del departamento de Direcci\u00f3n Comercial de IESE Business School.","breadcrumb":{"@id":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/#primaryimage","url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2018\/11\/Albert-Valenti-2025-b.jpg","contentUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2018\/11\/Albert-Valenti-2025-b.jpg","width":205,"height":205,"caption":"Albert Valent\u00ed | IESE Business School"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.edu\/es\/claustro-investigacion\/claustro\/albert-valenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iese.edu\/es\/"},{"@type":"ListItem","position":2,"name":"Albert Valent\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.edu\/es\/#website","url":"https:\/\/www.iese.edu\/es\/","name":"IESE","description":"","publisher":{"@id":"https:\/\/www.iese.edu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.edu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iese.edu\/es\/#organization","name":"IESE Business School","url":"https:\/\/www.iese.edu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/12\/Logo-IESE.png","contentUrl":"https:\/\/www.iese.edu\/es\/wp-content\/uploads\/sites\/2\/2020\/12\/Logo-IESE.png","width":290,"height":290,"caption":"IESE Business School"},"image":{"@id":"https:\/\/www.iese.edu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/professor\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/professor"}],"about":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/types\/professor"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/media\/19733"}],"wp:attachment":[{"href":"https:\/\/www.iese.edu\/es\/wp-json\/wp\/v2\/media?parent=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}