{"id":5997,"date":"2023-12-05T07:39:31","date_gmt":"2023-12-05T07:39:31","guid":{"rendered":"https:\/\/www.iese.edu\/standout\/?p=5997"},"modified":"2025-05-26T10:00:13","modified_gmt":"2025-05-26T10:00:13","slug":"cambio-como-lograr-jj-van-oosten","status":"publish","type":"post","link":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/","title":{"rendered":"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=\u00bb.vc_custom_1559140963143{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][vc_column css=\u00bb.vc_custom_1559216895048{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][vc_column_text css=\u00bb\u00bb]McKinsey afirma que el 70% de las transformaciones digitales fallan, siendo la resistencia de los empleados la causa m\u00e1s com\u00fan. Adem\u00e1s, solo el 16% de los empleados creen que las reformas digitales de sus empresas son sostenibles a largo plazo.<\/p>\n<p>\u00bfC\u00f3mo podemos hacerlo mejor? \u00bfC\u00f3mo podemos ganar m\u00e1s r\u00e1pidamente a las personas para nuestra causa? \u00bfY c\u00f3mo creamos un cambio que sea sostenible?<\/p>\n<p>Bueno, si alguien deber\u00eda saberlo\u2026 Jean-Jacques (JJ) Van Oosten ha sido llamado \u00abel alquimista\u00bb. Se describe a s\u00ed mismo como un \u00abtransformador digital en serie\u00bb. Ha liderado cinco transformaciones digitales y omnicanal exitosas y complejas en Rewe Group, Tesco, Travis Perkins, LEGO y Kingfisher.<\/p>\n<p>El profesor I\u00f1igo Gallo es Profesor Asociado de Marketing en IESE Business School, una de las mejores escuelas de negocios del mundo, clasificada como n\u00famero 1 en el mundo durante seis a\u00f1os consecutivos por el Financial Times.<\/p>\n<p>Este es el <strong>podcast de This is Real Leadership<\/strong>: En cada episodio, un l\u00edder empresarial comparte historias humanas y verdades dif\u00edciles de su carrera. Y un experto convierte esas historias en lecciones que todos podemos aprender.<\/p>\n<p>En este episodio, I\u00f1igo y JJ discuten:<\/p>\n<ul>\n<li>Las habilidades de comunicaci\u00f3n que necesitas para impulsar el cambio<\/li>\n<li>Factores comunes en todas las transformaciones empresariales exitosas<\/li>\n<li>\u00bfPor qu\u00e9 la gente se opone al cambio?<\/li>\n<li>\u00bfC\u00f3mo puedes ayudar a las personas que se resisten al cambio?<\/li>\n<\/ul>\n<h3>Escucha este podcast:<\/h3>\n<p><iframe style=\"border-radius: 12px;\" src=\"https:\/\/open.spotify.com\/embed\/episode\/5NL68QUahU5o1yMS6Qgm1H?utm_source=generator\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Para obtener m\u00e1s contenido como este, visita el\u00a0<a href=\"https:\/\/www.iese.edu\/es\/real-leadership\/\">sitio web de Real Leadership<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"text-decoration: underline;\">Transcripci\u00f3n del podcast:<\/span><\/h3>\n<p>Adam:<\/p>\n<p>Hola y bienvenidos a This is Real Leadership. Donde un destacado l\u00edder empresarial comparte historias humanas y verdades dif\u00edciles de toda su carrera. Y un experto convierte esas palabras en lecciones de las que todos podemos aprender.<\/p>\n<p>&nbsp;<\/p>\n<p>En este episodio, esas lecciones tratan sobre lograr que el cambio suceda. Y hacer que sea sostenible.<\/p>\n<p>&nbsp;<\/p>\n<p>Soy Adam Burns. He estado hablando y escribiendo sobre liderazgo empresarial durante m\u00e1s de 25 a\u00f1os y a\u00fan as\u00ed, cada d\u00eda es una lecci\u00f3n. Es por eso que, en este podcast, tambi\u00e9n me acompa\u00f1a ese experto: un distinguido profesor del IESE, una de las mejores escuelas de negocios del mundo, clasificada como n\u00famero 1 en el mundo durante seis a\u00f1os consecutivos.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n estar\u00e1 conversando con nuestro invitado. Y luego, solo conmigo. Ofreciendo su an\u00e1lisis experto de la conversaci\u00f3n, mientras pregunto: \u00bfcu\u00e1les son las verdaderas lecciones de liderazgo aqu\u00ed? \u00bfQu\u00e9 podemos aprender en los pr\u00f3ximos 30 minutos?<\/p>\n<p>&nbsp;<\/p>\n<p>Descubr\u00e1moslo. Bienvenido, Profesor I\u00f1igo Gallo.<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>Gracias, Adam. Muy contento de estar aqu\u00ed contigo hoy.<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>\u00a1Es genial tenerte de vuelta! I\u00f1igo, eres Profesor Asociado de Marketing en IESE. \u00bfEs el marketing una habilidad poco utilizada cuando se trata de crear y liderar transformaciones comerciales exitosas y sostenibles?<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>Una de las cosas que a menudo revisitamos en clase es lo que sucede con muchas startups; dedican mucho esfuerzo, mucho dinero, mucho tiempo y muchos recursos para desarrollar lo que piensan que el mercado necesita. Y luego, cuando terminan de desarrollarlo, se dan cuenta de que se han quedado sin dinero, se han quedado sin recursos. Y, solo usando ese ejemplo para esta discusi\u00f3n que vamos a tener hoy con JJ, estoy interesado en ver si esto es lo mismo en su experiencia; que muchas veces subestimamos la necesidad de comercializar exitosamente esto internamente, para superar esa resistencia. Esa resistencia, que seguramente va a aparecer. Entonces s\u00ed, por supuesto, debemos pensar en el cronograma, los recursos, la tecnolog\u00eda, los resultados y c\u00f3mo vamos a financiar esto. No hay duda: vamos a pensar en todas esas cosas. Pero, volviendo a mi ejemplo de startup, tambi\u00e9n necesitamos pensar en c\u00f3mo vamos a comercializar esto, al menos internamente. Y luego, por supuesto, c\u00f3mo vamos a comunicarlo a nuestros clientes. Pero, internamente, \u00bfqu\u00e9 podemos hacer para superar la resistencia que, por definici\u00f3n, encontraremos en muchas personas de la organizaci\u00f3n?<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>Gracias, I\u00f1igo. Y no creo que sea la \u00faltima vez que escuchemos sobre comunicaci\u00f3n o resistencia en este episodio.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan McKinsey, el 70% de las transformaciones digitales fallan, m\u00e1s a menudo debido a la resistencia, ah\u00ed lo tienen, de los empleados. Y solo el 16% de los empleados creen que las reformas digitales de su empresa son sostenibles a largo plazo. Entonces, \u00bfc\u00f3mo lo hacemos mejor?<\/p>\n<p>&nbsp;<\/p>\n<p>El invitado de hoy deber\u00eda saberlo. Jean-Jacques Van Oosten ha sido llamado \u00abel alquimista\u00bb. Se describe a s\u00ed mismo como un \u00abtransformador digital en serie\u00bb, habiendo liderado cinco transformaciones digitales y omnicanal exitosas y complejas en Rewe Group, Tesco, Travis Perkins, LEGO y Kingfisher. Comenzamos pregunt\u00e1ndole a JJ qu\u00e9 ten\u00edan en com\u00fan esos cinco proyectos de cambio&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>JJ Van Oosten:<\/p>\n<p>Creo que todos ten\u00edan un tipo de \u00abplataforma ardiente\u00bb en com\u00fan. Una necesidad absoluta de cambio debido al cambio en el comportamiento de los consumidores y clientes, comprando muchas m\u00e1s cosas en Internet. Pero tambi\u00e9n, debido a la competencia de los grandes marketplaces, y todos sabemos qui\u00e9nes son, ejerciendo mucha presi\u00f3n sobre su crecimiento. Ese es un elemento que pude ver. El segundo elemento que fue muy claro, y es muy importante, es que hab\u00eda expectativas muy altas, y un deseo y voluntad por parte del CEO y el presidente de esas empresas, de realmente hacer y lograr esos cambios. Pero no saben cu\u00e1les son los cambios. No saben c\u00f3mo hacerlo. Y hay un nivel de preocupaci\u00f3n, obviamente, que muchos de ellos tienen, y tambi\u00e9n miedo, porque muy pocas personas son capaces de disfrutar de la ambig\u00fcedad. Y esta ambig\u00fcedad, esta incertidumbre, subirse a un barco cuando sabes, m\u00e1s o menos, cu\u00e1l es el destino, pero no sabes muy bien c\u00f3mo llegar all\u00ed, requiere varias habilidades para reunir a todas esas personas.<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>Encuentro esto&#8230; realmente interesante para m\u00ed. Y lo he escuchado muchas veces en diferentes lugares, esta noci\u00f3n de no saber a d\u00f3nde vamos. Y estar c\u00f3modo con la ambig\u00fcedad, y todo eso. \u00bfC\u00f3mo se prepara a alguien para estar completamente desprevenido?<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>Lo que sucede en clase la mayor\u00eda de las veces es, vale, aqu\u00ed hay una gran decisi\u00f3n que la empresa enfrenta. Tenemos razones tanto para hacer A como para hacer B, pero no podemos hacer ambas al mismo tiempo. Y probablemente no hay una sola raz\u00f3n que gane el argumento. Y, por lo tanto, se trata realmente de sopesar los pros y los contras de ambas opciones. Y, al final, simplemente decir: \u00abEscucha. Intenta tener una idea de cu\u00e1l de las dos opciones es m\u00e1s fuerte o tiene m\u00e1s sentido, incluso si no es perfecta, y aunque no tenga solo pros y ventajas\u00bb. Y, una vez que decides, te atienes a eso y te esfuerzas por ello, porque nunca vas a tener un 100% de evidencia a favor de algo. Si ese fuera el caso, entonces no ser\u00eda una decisi\u00f3n dif\u00edcil de tomar. Por definici\u00f3n, si es una decisi\u00f3n dif\u00edcil, significa que hay m\u00e1s de una manera de hacerlo. Y as\u00ed, debes estar bien con no tener todos los datos, no tener todos los argumentos y tener esa ambig\u00fcedad de la que hablaba JJ.<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>\u00bfCrees, JJ, que es importante tener un sesgo hacia la acci\u00f3n?<\/p>\n<p>&nbsp;<\/p>\n<p>JJ Van Oosten:<\/p>\n<p>Creo que eso ayuda. Pero lo crucial y esencial es articular, muy r\u00e1pidamente y de manera muy simplificada, los resultados esperados, en t\u00e9rminos del qu\u00e9 y el c\u00f3mo. Y el sesgo hacia la acci\u00f3n entra ah\u00ed, porque necesitas hacer eso muy r\u00e1pidamente. Y la habilidad que tengo, realmente, en mi mente, y tengo que mantenerme fiel a ella, es mantener esa simplicidad en torno a los resultados esperados, en t\u00e9rminos del qu\u00e9 y el c\u00f3mo. Y asegurarme de que la complejidad de la organizaci\u00f3n y el entorno no diluyan la simplicidad a la que nos hemos alineado. Cuando tienes esa simplicidad, entonces tienes una historia. Y cuando tengo una historia, debe adaptarse a la cultura de la empresa, la historia de la empresa, y debe ser lo suficientemente simple como para que cualquier persona que trabaje en una tienda, o cualquier cliente que entre en cualquiera de nuestras tiendas, o cualquier persona en un centro de llamadas, o en un chat en l\u00ednea para comercio electr\u00f3nico, pueda entenderlo en segundos. Y eso es dif\u00edcil.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Entonces, los proyectos de transformaci\u00f3n exitosos tienen una raz\u00f3n para el cambio claramente definida y comprendida, el deseo y la voluntad del Director Ejecutivo, y una comunicaci\u00f3n constante sobre resultados simples. Y necesitas la simplicidad, porque est\u00e1s llevando a las personas a un lugar donde se espera que se sientan c\u00f3modas con la falta de conocimiento. Con la ambig\u00fcedad. El viaje en s\u00ed mismo es confuso, por lo que al menos el destino deber\u00eda ser claro.<\/p>\n<p>&nbsp;<\/p>\n<p>La pr\u00f3xima parte de nuestra conversaci\u00f3n, sin embargo, trata sobre por qu\u00e9, incluso si tienes todas las cosas que acabo de mencionar en su lugar, por qu\u00e9 la gente a\u00fan se resiste al cambio. Y qu\u00e9 puedes hacer al respecto.<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>Mi impresi\u00f3n es que, en todos estos proyectos, por importantes y cruciales que sean para las empresas, la mayor resistencia es probablemente la resistencia de las personas. As\u00ed que, dentro de la organizaci\u00f3n, creo que hay varias razones por las que la gente lo rechaza. Por qu\u00e9 todos lo rechazamos, yo incluido. Esta es probablemente una condici\u00f3n humana natural de que, \u00abEh, en promedio, no estoy tan emocionado con el cambio\u00bb. Tal vez tambi\u00e9n est\u00e1 el sentido de que las cosas tradicionales todav\u00eda funcionan, y hay muchas cosas tradicionales que todav\u00eda funcionan. Entonces, \u00bfpor qu\u00e9 tenemos que ir tan r\u00e1pido? \u00bfPor qu\u00e9 tenemos que cambiar tantas cosas? Tal vez tambi\u00e9n est\u00e1 el recuerdo de fracasos pasados. S\u00ed, intentamos este cambio tecnol\u00f3gico, o lo que sea, hace muchos a\u00f1os, y fue un completo desastre. Y, vinculado a esto, tal vez tambi\u00e9n est\u00e1 la sensaci\u00f3n de: \u00abVamos a ver c\u00f3mo lo hacen los dem\u00e1s, y luego saltaremos una vez que est\u00e9 probado\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>JJ Van Oosten:<\/p>\n<p>Y todos piensan que est\u00e1n sirviendo a sus clientes todos los d\u00edas, pero la mayor\u00eda de ellos no sabe qui\u00e9nes son sus clientes. La pregunta real, y aqu\u00ed es donde est\u00e1 la resistencia, es c\u00f3mo cambiamos nuestro h\u00e1bito de simplemente pensar en productos, formatos y procesos que han sido muy exitosos, como dec\u00eda I\u00f1igo, durante muchos a\u00f1os, y agregamos una dimensi\u00f3n de clientes. Diciendo, \u00abVale, \u00bfqui\u00e9nes son esos clientes que tengo? \u00bfCu\u00e1ntos necesito realmente para que funcione este presupuesto? \u00bfCu\u00e1nto me cuesta adquirir nuevos clientes? \u00bfCu\u00e1nto me cuesta? Y \u00bfcu\u00e1l es la mejor manera de retenerlos?\u00bb Y, agregar esa nueva dimensi\u00f3n a todo tu pensamiento es bastante dif\u00edcil de hacer, siendo honestos. Porque nadie quiere admitir que no sabe qui\u00e9nes son sus clientes. Nadie quiere admitir que no est\u00e1n sirviendo a sus clientes de la mejor manera posible todos los d\u00edas. Y eso es un gran cambio.<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>Realmente me gusta c\u00f3mo lo has expresado; que a nadie le gusta admitir que no conoce a sus clientes. Creo que esto es crucial. Y creo que, muchas veces, esto es algo que surge en clase y en muchas discusiones: no eres una representaci\u00f3n justa de tu mercado. Y as\u00ed, lo primero que necesitamos hacer es eliminar nuestros propios prejuicios. Y cuanto m\u00e1s tiempo hayas estado en el negocio, m\u00e1s necesitas esto, \u00bfverdad? Porque la tentaci\u00f3n de decirte a ti mismo \u00abYa lo s\u00e9\u00bb se vuelve m\u00e1s grande cuanto m\u00e1s a\u00f1os llevas en ello, especialmente si has tenido \u00e9xito. Y as\u00ed, tiendes a pensar, \u00abTodos mis clientes, m\u00e1s o menos, se comportan de la manera en que yo lo hago\u00bb. Esto es simplemente una condici\u00f3n humana, supongo, que tendemos a pensar de esa manera.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>Entonces, si quieres llevar a cabo un cambio de manera efectiva, \u00bfnecesitas traer a alguien de fuera de la empresa? \u00bfEs realmente muy dif\u00edcil hacerlo si has estado en esa empresa durante mucho tiempo? \u00bfNecesitas una perspectiva nueva, una voz fresca?<\/p>\n<p>&nbsp;<\/p>\n<p>JJ Van Oosten:<\/p>\n<p>Sabes, si has hecho los mismos movimientos todos los d\u00edas, por ejemplo, si has estado corriendo todos los d\u00edas durante los \u00faltimos 20 a\u00f1os, pero no has nadado, o si no has hecho levantamiento de pesas, o lo que sea, hacer un cambio no es agradable. Es doloroso, o parte de ello es doloroso, porque es un nuevo h\u00e1bito que debes adquirir. Y entonces, definitivamente hay algo que abordar ah\u00ed. Cuando haces esos cambios, a veces traes a un entrenador para ayudarte a aprender estas nuevas habilidades, para que no te lastimes y para que aprendas m\u00e1s r\u00e1pido. Y en cuanto a la cuesti\u00f3n de externalizar tu transformaci\u00f3n, creo que esto es, en mi opini\u00f3n personal, algo muy peligroso.<\/p>\n<p>&nbsp;<\/p>\n<p>Nos resistimos al cambio porque pensamos que todo est\u00e1 bien, o porque lo hemos intentado antes, o porque hemos sido suavemente institucionalizados. Y algunas formas de superar eso son volver a enfocarse, adecuadamente, sin prejuicios, en lo que realmente quieren tus clientes. Traer a un entrenador para ayudarte a agregar nuevos ejercicios a tu rutina diaria de ejercicios f\u00edsicos.<\/p>\n<p>&nbsp;<\/p>\n<p>Y dar a tus equipos la oportunidad no solo de ser parte de esa transformaci\u00f3n, sino de darle forma. De crear su propio futuro sin miedo al fracaso.<\/p>\n<p>&nbsp;<\/p>\n<p>JJ cree que se logra este \u00faltimo punto mediante la creaci\u00f3n de espacios seguros. Crucialmente, aunque son seguros, no son carentes de desaf\u00edos.<\/p>\n<p>&nbsp;<\/p>\n<p>JJ Van Oosten:<\/p>\n<p>Hay dos aspectos en ello. El primero es que, es un poco clich\u00e9, pero todos son bienvenidos. Y nadie ser\u00e1 criticado por lo que diga, siempre y cuando est\u00e9 dentro de los l\u00edmites \u00e9ticos. Y aquellos que no hablan tendr\u00e1n el tiempo y la oportunidad. Espec\u00edficamente busco a esas personas tambi\u00e9n para que realmente hablen. Porque algunos son muy introvertidos y silenciosos, pero a veces esas personas tienen mucho que aportar y hay que respetarlo. Eso es muy importante. La interfuncionalidad: sacar a las personas de sus silos, reunirlos en equipos interfuncionales que trabajen en marketing, cadena de suministro, finanzas, tecnolog\u00eda, dise\u00f1o de productos, etc., y hacer que trabajen en problemas que son muy complejos de resolver. \u00bfC\u00f3mo hacer que una nueva cocina est\u00e9 disponible y accesible para familias de bajos ingresos, con todas las caracter\u00edsticas de uso de menos agua, electricidad, etc.? Estos son problemas grandes y complejos para resolver. \u00bfC\u00f3mo asegurarse de que la informaci\u00f3n sea f\u00e1cilmente comprensible en internet tambi\u00e9n? Entonces, esos equipos est\u00e1n trabajando en eso. Y por definici\u00f3n, desafiar\u00e1n algunas pr\u00e1cticas existentes. Es muy importante crear un ambiente donde puedan hacer esto y realmente puedan ser recompensados por eso. Y si fallan, porque toman riesgos, deber\u00edas celebrar tambi\u00e9n algunos fracasos. Y eso est\u00e1 bien. La capacidad de reconocer que esto es un fracaso, detenerlo y no continuar, este es un gran cambio de mentalidad. Y luego, a nivel m\u00e1s alto, detr\u00e1s de puertas cerradas, parte de mi trabajo es llamar la atenci\u00f3n sobre ciertos comportamientos que no son aceptables de otros ejecutivos. Y eso es porque ellos tambi\u00e9n tienen que pasar por sus propios cambios. Pero si piensan que est\u00e1n perdiendo poder, o lo que sea, o si vienen con sorpresas, etc., que sucede todo el tiempo, entonces, termino el d\u00eda y digo que eso no es aceptable. Y usualmente lo que sucede despu\u00e9s de esas discusiones dif\u00edciles en lo m\u00e1s alto, cuando algunos comportamientos quiz\u00e1s no est\u00e9n completamente alineados, por lo general, despu\u00e9s de unas horas o unos d\u00edas, volvemos a ser los mejores amigos. Por eso es importante la forma en que lo haces. Porque, podr\u00edas disculparte o lo que sea, pero siempre es con las mejores intenciones. Nunca es personal. Y nunca me involucro personalmente en la guerra de palabras, porque entonces la complejidad de la organizaci\u00f3n existente y la cultura existente realmente arrastrar\u00e1n la simplicidad de la transformaci\u00f3n y los resultados esperados, y ralentizar\u00e1n todo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>Entrevist\u00e9 a alguien, de hecho, hace unos 10 a\u00f1os, quien lider\u00f3 una fusi\u00f3n y adquisici\u00f3n s\u00faper grande en la industria farmac\u00e9utica. Y dijo algo que se me ha quedado grabado. Dijo: \u00abLas personas que descarrilar\u00e1n tu proyecto no son las que dicen no a tu cara. Son aquellos que dicen s\u00ed a tu cara, pero no detr\u00e1s de ti\u00bb. Los llam\u00f3 &#8216;resistentes pasivos&#8217;. \u00bfC\u00f3mo lidiar\u00edas con ellos?<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>S\u00ed. Imagino que esto tiene que ver con algo que JJ mencion\u00f3 al principio. Creo, si recuerdo bien, que JJ mencion\u00f3 que las dos cosas comunes que ha experimentado en las transformaciones que ha liderado son que eran necesarias, y hablaste sobre los cambios en el consumidor y los cambios en la competencia. Pero tambi\u00e9n, creo que mencionaste, JJ, que hab\u00eda un inter\u00e9s fuerte, claro y expl\u00edcito por parte del CEO, o de quien estuviera a cargo. De lo contrario, supongo, JJ, que es una guerra muy dif\u00edcil de librar, o para ponerlo de manera m\u00e1s positiva, un conflicto muy dif\u00edcil de manejar.<\/p>\n<p>&nbsp;<\/p>\n<p>JJ Van Oosten:<\/p>\n<p>No es posible, para ser honesto. As\u00ed que, por eso, he hecho cinco, pero siempre me tomo tiempo. Tambi\u00e9n aprend\u00ed de eso. Tomo tiempo al principio, si tienes entrevistas, o lo que sea. Pero tambi\u00e9n entrevisto a la empresa y al equipo ejecutivo, y al director ejecutivo y al presidente. Porque, \u00bfrealmente entienden las consecuencias de los resultados esperados que creen que quieren tener? \u00bfRealmente entienden? Porque nuestro trabajo como ejecutivos senior es bastante simple. Es dar prioridades absolutas, y no muchas: unas pocas, prioridades claras. Y nuestro otro trabajo es dar los recursos a los equipos para que realmente tengan \u00e9xito. Pero, como los recursos no son solo personas y dinero, tambi\u00e9n es nuestro trabajo, cuando encuentran obst\u00e1culos, eliminar esos obst\u00e1culos para ellos. Y necesitan poder hacerlo, no viniendo con 60 p\u00e1ginas de PowerPoint, sino hacerlo muy r\u00e1pido. Todas las formas de trabajar basadas en datos y automatizaciones deben permitirnos, como equipo, de arriba a abajo y de abajo a arriba, tener visibilidad y transparencia de lo que est\u00e1 sucediendo. Y, muy claramente, muy r\u00e1pido, cuando sea necesario; podr\u00eda ser todos los d\u00edas al principio, pero esto a menudo no es el caso&#8230; Sobre los bloqueos m\u00e1s importantes, podr\u00eda tratarse de \u201cNo podemos tener los mismos SKU de estos proveedores que hemos estado vendiendo durante 20 a\u00f1os, etc.\u201d, y eso crea conflictos, o podr\u00eda tratarse de archivos de atributos del producto, podr\u00eda ser sobre estrategias y decisiones de precios, podr\u00eda ser sobre la forma en que arquitectas las cosas, podr\u00eda ser sobre algunas agencias que podr\u00edamos estar usando en marketing, o lo que sea. Todo esto puede bloquear a algunos equipos para avanzar. Y debes asegurarte de desbloquear eso muy r\u00e1pidamente.<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>I\u00f1igo, es tu turno para compartir tus reflexiones. Prometimos lecciones empresariales reales que se puedan utilizar. \u00bfQu\u00e9 aprendiste? \u00bfQu\u00e9 conclusiones sacas de JJ?<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>Creo que algo que me gust\u00f3 mucho es cuando describi\u00f3 la responsabilidad de un ejecutivo de alto nivel en una organizaci\u00f3n. Mencion\u00f3 dos cosas, que creo que probablemente ha aprendido de sus proyectos de transformaci\u00f3n, pero que creo que se pueden generalizar a todo. Mencion\u00f3 que los ejecutivos de alto nivel hacen dos cosas. Establecen prioridades, solo unas pocas, muy claras, y proporcionan recursos para los equipos. As\u00ed que, esas dos cosas son parte del trabajo de un ejecutivo de alto nivel. Tambi\u00e9n me gust\u00f3 cuando habl\u00f3 sobre c\u00f3mo, en un proyecto tan grande como transformar una organizaci\u00f3n, hay que hacer un esfuerzo muy, muy grande para articular los resultados esperados. Y de nuevo, solo unos pocos, un pu\u00f1ado, no muchos. Pero, ser muy claro sobre qu\u00e9 es lo que esperas. Y luego, el \u00faltimo que mencionamos, y que tambi\u00e9n me gust\u00f3, es esta necesidad de crear espacios seguros para el cambio. Creo que esto se relaciona mucho con otros podcasts que hemos hecho, sobre aprender de los errores, con Elena. Creo que eso se refiere mucho a esto.<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>Realmente se trata mucho del equipo, \u00bfverdad? Se trata mucho de las personas que se ayudan mutuamente.<\/p>\n<p>&nbsp;<\/p>\n<p>I\u00f1igo Gallo:<\/p>\n<p>S\u00ed, creo que estaba constantemente presente el tema de sumar a la gente, entender a las personas, resolver conflictos.<\/p>\n<p>&nbsp;<\/p>\n<p>Adam:<\/p>\n<p>Gracias al Profesor I\u00f1igo Gallo, Profesor Asociado de Marketing en IESE Business School. Y gracias, por supuesto, por escuchar. Por favor, suscr\u00edbete, comparte y cu\u00e9ntanos qu\u00e9 piensas de nuestro podcast. \u00bfLas empresas son de un solo uso o son la rareza de las bestias: leopardos que pueden cambiar sus manchas? \u00bfPiensas diferente a JJ e I\u00f1igo? Por favor, h\u00e1znoslo saber en los comentarios o env\u00edanos un correo electr\u00f3nico. Nos encantar\u00eda saber de ti. Todos los detalles est\u00e1n en la descripci\u00f3n del podcast. Pero, por ahora, por mi parte, adi\u00f3s.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1559140963143{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][vc_column css=\u00bb.vc_custom_1559216895048{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][vc_column_text css=\u00bb\u00bb]McKinsey&#8230;<\/p>\n","protected":false},"author":4,"featured_media":5994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,113],"tags":[52,77],"class_list":{"0":"post-5997","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-general-es","8":"category-general-es-2","9":"tag-general-management-es","10":"tag-people-es"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo crear un cambio sostenible en la empresa?JJ Van Oosten, transformador digital en serie, en el podcast This is Real Leadership de IESE Business School.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo crear un cambio sostenible en la empresa?JJ Van Oosten, transformador digital en serie, en el podcast This is Real Leadership de IESE Business School.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\" \/>\n<meta property=\"og:site_name\" content=\"IESE Standout\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"IESE Standout\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"IESE Standout\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\"},\"author\":{\"name\":\"IESE Standout\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/person\/fd2c3dde438ee9ebca29aeec067df184\"},\"headline\":\"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\"},\"wordCount\":3734,\"publisher\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg\",\"keywords\":[\"General Management\",\"People\"],\"articleSection\":[\"General\",\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\",\"url\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\",\"name\":\"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)\",\"isPartOf\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg\",\"datePublished\":\"2023-12-05T07:39:31+00:00\",\"dateModified\":\"2025-05-26T10:00:13+00:00\",\"description\":\"\u00bfC\u00f3mo crear un cambio sostenible en la empresa?JJ Van Oosten, transformador digital en serie, en el podcast This is Real Leadership de IESE Business School.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage\",\"url\":\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg\",\"contentUrl\":\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.iese.edu\/standout\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#website\",\"url\":\"https:\/\/www.iese.edu\/standout\/es\/\",\"name\":\"IESE Standout\",\"description\":\"IESE Business School\",\"publisher\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.iese.edu\/standout\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#organization\",\"name\":\"IESE Business School\",\"url\":\"https:\/\/www.iese.edu\/standout\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2020\/11\/Logo-IESE-Business-School.png\",\"contentUrl\":\"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2020\/11\/Logo-IESE-Business-School.png\",\"width\":290,\"height\":290,\"caption\":\"IESE Business School\"},\"image\":{\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/person\/fd2c3dde438ee9ebca29aeec067df184\",\"name\":\"IESE Standout\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/361aacf621d488c9e3bee750c5665077c4cf539f0c4f8e6d206bb927aa36eead?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/361aacf621d488c9e3bee750c5665077c4cf539f0c4f8e6d206bb927aa36eead?s=96&d=mm&r=g\",\"caption\":\"IESE Standout\"},\"url\":\"https:\/\/www.iese.edu\/standout\/es\/author\/standout\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)","description":"\u00bfC\u00f3mo crear un cambio sostenible en la empresa?JJ Van Oosten, transformador digital en serie, en el podcast This is Real Leadership de IESE Business School.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)","og_description":"\u00bfC\u00f3mo crear un cambio sostenible en la empresa?JJ Van Oosten, transformador digital en serie, en el podcast This is Real Leadership de IESE Business School.","og_url":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/","og_site_name":"IESE Standout","og_image":[{"width":1000,"height":666,"url":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg","type":"image\/jpeg"}],"author":"IESE Standout","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"IESE Standout","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#article","isPartOf":{"@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/"},"author":{"name":"IESE Standout","@id":"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/person\/fd2c3dde438ee9ebca29aeec067df184"},"headline":"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)","mainEntityOfPage":{"@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/"},"wordCount":3734,"publisher":{"@id":"https:\/\/www.iese.edu\/standout\/es\/#organization"},"image":{"@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg","keywords":["General Management","People"],"articleSection":["General","General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/","url":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/","name":"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)","isPartOf":{"@id":"https:\/\/www.iese.edu\/standout\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg","datePublished":"2023-12-05T07:39:31+00:00","dateModified":"2025-05-26T10:00:13+00:00","description":"\u00bfC\u00f3mo crear un cambio sostenible en la empresa?JJ Van Oosten, transformador digital en serie, en el podcast This is Real Leadership de IESE Business School.","breadcrumb":{"@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#primaryimage","url":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg","contentUrl":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2023\/12\/PHOTO-STANDOUT-PODCAST.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.edu\/standout\/es\/cambio-como-lograr-jj-van-oosten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iese.edu\/standout\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo lograr que ocurra el cambio. Con JJ Van Oosten (Podcast)"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.edu\/standout\/es\/#website","url":"https:\/\/www.iese.edu\/standout\/es\/","name":"IESE Standout","description":"IESE Business School","publisher":{"@id":"https:\/\/www.iese.edu\/standout\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.edu\/standout\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iese.edu\/standout\/es\/#organization","name":"IESE Business School","url":"https:\/\/www.iese.edu\/standout\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2020\/11\/Logo-IESE-Business-School.png","contentUrl":"https:\/\/www.iese.edu\/standout\/wp-content\/uploads\/2020\/11\/Logo-IESE-Business-School.png","width":290,"height":290,"caption":"IESE Business School"},"image":{"@id":"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/person\/fd2c3dde438ee9ebca29aeec067df184","name":"IESE Standout","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iese.edu\/standout\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/361aacf621d488c9e3bee750c5665077c4cf539f0c4f8e6d206bb927aa36eead?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/361aacf621d488c9e3bee750c5665077c4cf539f0c4f8e6d206bb927aa36eead?s=96&d=mm&r=g","caption":"IESE Standout"},"url":"https:\/\/www.iese.edu\/standout\/es\/author\/standout\/"}]}},"menu_order":3,"_links":{"self":[{"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/posts\/5997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/comments?post=5997"}],"version-history":[{"count":8,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/posts\/5997\/revisions"}],"predecessor-version":[{"id":6732,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/posts\/5997\/revisions\/6732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/media\/5994"}],"wp:attachment":[{"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/media?parent=5997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/categories?post=5997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.edu\/standout\/es\/wp-json\/wp\/v2\/tags?post=5997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}